{"id":1875,"date":"2011-04-04T00:00:00","date_gmt":"2011-04-03T22:00:00","guid":{"rendered":"https:\/\/www.gereso.com\/actualites\/2011\/04\/signature-des-courriers-de-licenciement\/"},"modified":"2011-04-04T00:00:00","modified_gmt":"2011-04-03T22:00:00","slug":"signature-des-courriers-de-licenciement","status":"publish","type":"post","link":"https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/","title":{"rendered":"Signature des courriers de licenciement"},"content":{"rendered":"<p class=\"titre\"><span>La Cour de cassation estime qu&rsquo;un int\u00e9rimaire en mission \u00e0 la DRH peut signer les courriers de licenciement. En l&rsquo;esp\u00e8ce, plusieurs salari\u00e9s d&rsquo;une soci\u00e9t\u00e9 licenci\u00e9s pour motif \u00e9conomique estimaient que le signataire des lettres de licenciement n&rsquo;avait pas qualit\u00e9 pour le faire. Leurs courriers de licenciement avaient \u00e9t\u00e9 sign\u00e9s par un int\u00e9rimaire, alors en mission de travail temporaire au sein de la direction des ressources humaines. La Cour de cassation ne suit pas le raisonnement. Elle estime que cet int\u00e9rimaire ayant pour mission l&rsquo;assistance et le conseil du DRH ainsi que son remplacement \u00e9ventuel, il a le pouvoir de signer les lettres de licenciement.<\/span><\/p>\n<p class=\"titre\"><span>Source : Cass. soc. 2 mars 2011, n\u00b0 09-67237 FPPB<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Cour de cassation estime qu&rsquo;un int\u00e9rimaire en mission \u00e0 la DRH peut signer les courriers de licenciement. En l&rsquo;esp\u00e8ce, plusieurs salari\u00e9s d&rsquo;une soci\u00e9t\u00e9 licenci\u00e9s pour motif \u00e9conomique estimaient que le signataire des lettres de licenciement n&rsquo;avait pas qualit\u00e9 pour le faire. Leurs courriers de licenciement avaient \u00e9t\u00e9 sign\u00e9s par un int\u00e9rimaire, alors en mission [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_mi_skip_tracking":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1875","post","type-post","status-publish","format-standard","hentry","category-droit-du-travail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Signature des courriers de licenciement - Le Blog GERESO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Signature des courriers de licenciement - Le Blog GERESO\" \/>\n<meta property=\"og:description\" content=\"La Cour de cassation estime qu&rsquo;un int\u00e9rimaire en mission \u00e0 la DRH peut signer les courriers de licenciement. En l&rsquo;esp\u00e8ce, plusieurs salari\u00e9s d&rsquo;une soci\u00e9t\u00e9 licenci\u00e9s pour motif \u00e9conomique estimaient que le signataire des lettres de licenciement n&rsquo;avait pas qualit\u00e9 pour le faire. Leurs courriers de licenciement avaient \u00e9t\u00e9 sign\u00e9s par un int\u00e9rimaire, alors en mission [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Blog GERESO\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-03T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"\u00c9quipe GERESO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/\",\"url\":\"https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/\",\"name\":\"Signature des courriers de licenciement - Le Blog GERESO\",\"isPartOf\":{\"@id\":\"https:\/\/www.gereso.com\/actualites\/#website\"},\"datePublished\":\"2011-04-03T22:00:00+00:00\",\"dateModified\":\"2011-04-03T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/197d8aef40cb4ae3f6a0aa9e1d3df2a6\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.gereso.com\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Signature des courriers de licenciement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/#website\",\"url\":\"https:\/\/www.gereso.com\/actualites\/\",\"name\":\"Le Blog GERESO\",\"description\":\"Toute l&#039;actu RH, Finance, Fonction Publique, Management...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gereso.com\/actualites\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/197d8aef40cb4ae3f6a0aa9e1d3df2a6\",\"name\":\"\u00c9quipe GERESO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2013\/12\/avatar-gereso-1.png\",\"contentUrl\":\"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2013\/12\/avatar-gereso-1.png\",\"caption\":\"\u00c9quipe GERESO\"},\"url\":\"https:\/\/www.gereso.com\/actualites\/author\/gereso\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Signature des courriers de licenciement - Le Blog GERESO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/","og_locale":"fr_FR","og_type":"article","og_title":"Signature des courriers de licenciement - Le Blog GERESO","og_description":"La Cour de cassation estime qu&rsquo;un int\u00e9rimaire en mission \u00e0 la DRH peut signer les courriers de licenciement. En l&rsquo;esp\u00e8ce, plusieurs salari\u00e9s d&rsquo;une soci\u00e9t\u00e9 licenci\u00e9s pour motif \u00e9conomique estimaient que le signataire des lettres de licenciement n&rsquo;avait pas qualit\u00e9 pour le faire. Leurs courriers de licenciement avaient \u00e9t\u00e9 sign\u00e9s par un int\u00e9rimaire, alors en mission [&hellip;]","og_url":"https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/","og_site_name":"Le Blog GERESO","article_published_time":"2011-04-03T22:00:00+00:00","author":"\u00c9quipe GERESO","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/","url":"https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/","name":"Signature des courriers de licenciement - Le Blog GERESO","isPartOf":{"@id":"https:\/\/www.gereso.com\/actualites\/#website"},"datePublished":"2011-04-03T22:00:00+00:00","dateModified":"2011-04-03T22:00:00+00:00","author":{"@id":"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/197d8aef40cb4ae3f6a0aa9e1d3df2a6"},"breadcrumb":{"@id":"https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.gereso.com\/actualites\/2011\/04\/04\/signature-des-courriers-de-licenciement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gereso.com\/actualites\/"},{"@type":"ListItem","position":2,"name":"Signature des courriers de licenciement"}]},{"@type":"WebSite","@id":"https:\/\/www.gereso.com\/actualites\/#website","url":"https:\/\/www.gereso.com\/actualites\/","name":"Le Blog GERESO","description":"Toute l&#039;actu RH, Finance, Fonction Publique, Management...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gereso.com\/actualites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/197d8aef40cb4ae3f6a0aa9e1d3df2a6","name":"\u00c9quipe GERESO","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2013\/12\/avatar-gereso-1.png","contentUrl":"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2013\/12\/avatar-gereso-1.png","caption":"\u00c9quipe GERESO"},"url":"https:\/\/www.gereso.com\/actualites\/author\/gereso\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/posts\/1875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/comments?post=1875"}],"version-history":[{"count":0,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/posts\/1875\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/media?parent=1875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/categories?post=1875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/tags?post=1875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}