{"id":24877,"date":"2021-12-29T12:56:43","date_gmt":"2021-12-29T10:56:43","guid":{"rendered":"https:\/\/www.gereso.com\/actualites\/?p=24877"},"modified":"2021-12-29T12:56:45","modified_gmt":"2021-12-29T10:56:45","slug":"loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel","status":"publish","type":"post","link":"https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/","title":{"rendered":"Loi de finances pour 2022 : validation par le Conseil constitutionnel"},"content":{"rendered":"\n<p>Le <strong>Conseil constitutionnel<\/strong> a valid\u00e9 ce mardi 28 d\u00e9cembre 2021 l\u2019essentiel des dispositions de la <strong>loi de finances pour 2022<\/strong>. Seuls 10 cavaliers l\u00e9gislatifs ont \u00e9t\u00e9 censur\u00e9s.<\/p>\n<h2><strong>Un budget consid\u00e9r\u00e9 comme sinc\u00e8re<\/strong><\/h2>\n<p>Adopt\u00e9e en lecture d\u00e9finitive le 15 d\u00e9cembre dernier par les d\u00e9put\u00e9s, la loi de finances pour 2022 a fait l\u2019objet de 3 recours du <strong>Conseil constitutionnel<\/strong>, notamment par plus de 60 d\u00e9put\u00e9s et plus de 60 s\u00e9nateurs. Leur grief principal concernait le s\u00e9rieux et <strong>la sinc\u00e9rit\u00e9 des mesures adopt\u00e9es<\/strong>. Beaucoup de parlementaires de l\u2019opposition consid\u00e8rent que ce budget ne prend pas en compte les cons\u00e9quences budg\u00e9taires de plusieurs mesures nouvelles annonc\u00e9es par le Gouvernement avant le d\u00e9p\u00f4t du projet de loi de finances.<\/p>\n<p>Selon eux, le budget 2022 ne tiendrait pas compte des d\u00e9penses li\u00e9es au plan d\u2019investissement \u00ab\u00a0<strong>France 2030<\/strong>\u00a0\u00bb, au revenu d\u2019engagement pour les jeunes et du plan \u00ab\u00a0Grand Marseille\u00a0\u00bb. Les auteurs des 3 recours se sont notamment appuy\u00e9s sur l\u2019avis du <strong>Haut conseil des finances publiques<\/strong> rendu le 17 septembre 2021, dans lequel ce dernier a affirm\u00e9 ne pas pouvoir \u00ab\u00a0rendre un avis pleinement \u00e9clair\u00e9 sur les pr\u00e9visions de finances publiques pour 2022\u00a0\u00bb.<\/p>\n<p>Dans sa d\u00e9cision rendue le 28 d\u00e9cembre 2021 (<a href=\"https:\/\/www.conseil-constitutionnel.fr\/decision\/2021\/2021833DC.htm\">d\u00e9cision n\u00b02021-833 DC du 28 d\u00e9cembre 2021<\/a>), les Sages ont \u00e9cart\u00e9 les griefs tir\u00e9s de la m\u00e9connaissance du principe de <strong>sinc\u00e9rit\u00e9 budg\u00e9taire<\/strong>. Ils estiment notamment que les hypoth\u00e8ses \u00e9conomiques retenues ne sont pas entach\u00e9es d\u2019une intention de fausser les grandes lignes de l\u2019\u00e9quilibre budg\u00e9taire.<\/p>\n<h2><strong>10 cavaliers budg\u00e9taires<\/strong><\/h2>\n<p>Comme la plupart des ann\u00e9es, si le Conseil constitutionnel a valid\u00e9 l\u2019essentiel de la loi de finances, il a n\u00e9anmoins censur\u00e9 plusieurs dispositions, 10 en tout, constituant des \u00ab\u00a0<strong>cavaliers budg\u00e9taires<\/strong>\u00a0\u00bb, c\u2019est-\u00e0-dire des mesures qui ne sont pas conformes \u00e0 l\u2019objet d\u2019une loi de finances. Il s\u2019agit d\u2019un probl\u00e8me de forme ne remettant pas en cause la constitutionnalit\u00e9 de ces dispositions. Le Gouvernement pourra les reproposer dans le cadre d\u2019un autre texte de loi plus appropri\u00e9.<\/p>\n<p>Les mesures rejet\u00e9es concernent notamment l\u2019article 93 qui ratifie l\u2019ordonnance 2021-1190 relative \u00e0 l\u2019instauration de <strong>l\u2019obligation de la facturation \u00e9lectronique<\/strong> et plusieurs mesures en mati\u00e8re sociale relative \u00e0 l\u2019<strong>OETH<\/strong> (obligation d\u2019emploi des travailleurs handicap\u00e9s). L\u2019article 118 qui permettait aux associations interm\u00e9diaires de ne plus tenir compte dans leur effectif des salari\u00e9s mis \u00e0 disposition a ainsi \u00e9t\u00e9 censur\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Conseil constitutionnel a valid\u00e9 ce mardi 28 d\u00e9cembre 2021 l\u2019essentiel des dispositions de la loi de finances pour 2022. Seuls 10 cavaliers l\u00e9gislatifs ont \u00e9t\u00e9 censur\u00e9s. Un budget consid\u00e9r\u00e9 comme sinc\u00e8re Adopt\u00e9e en lecture d\u00e9finitive le 15 d\u00e9cembre dernier par les d\u00e9put\u00e9s, la loi de finances pour 2022 a fait l\u2019objet de 3 recours [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"quote","meta":{"_acf_changed":false,"_mi_skip_tracking":false,"footnotes":""},"categories":[12,3],"tags":[1267,986],"class_list":["post-24877","post","type-post","status-publish","format-quote","hentry","category-actualites","category-comptabilite-fiscalite-et-gestion-financiere","tag-conseil-constitutionnel","tag-loi-de-finances","post_format-post-format-quote"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Loi de finances pour 2022 : validation par le Conseil constitutionnel - Le Blog GERESO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Loi de finances pour 2022 : validation par le Conseil constitutionnel - Le Blog GERESO\" \/>\n<meta property=\"og:description\" content=\"Le Conseil constitutionnel a valid\u00e9 ce mardi 28 d\u00e9cembre 2021 l\u2019essentiel des dispositions de la loi de finances pour 2022. Seuls 10 cavaliers l\u00e9gislatifs ont \u00e9t\u00e9 censur\u00e9s. Un budget consid\u00e9r\u00e9 comme sinc\u00e8re Adopt\u00e9e en lecture d\u00e9finitive le 15 d\u00e9cembre dernier par les d\u00e9put\u00e9s, la loi de finances pour 2022 a fait l\u2019objet de 3 recours [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Blog GERESO\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-29T10:56:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-29T10:56:45+00:00\" \/>\n<meta name=\"author\" content=\"Damien P\u00e9an\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/\",\"url\":\"https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/\",\"name\":\"Loi de finances pour 2022 : validation par le Conseil constitutionnel - Le Blog GERESO\",\"isPartOf\":{\"@id\":\"https:\/\/www.gereso.com\/actualites\/#website\"},\"datePublished\":\"2021-12-29T10:56:43+00:00\",\"dateModified\":\"2021-12-29T10:56:45+00:00\",\"author\":{\"@id\":\"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/c91814f92d627ed4715993fbbf7c7e8d\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.gereso.com\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loi de finances pour 2022 : validation par le Conseil constitutionnel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/#website\",\"url\":\"https:\/\/www.gereso.com\/actualites\/\",\"name\":\"Le Blog GERESO\",\"description\":\"Toute l&#039;actu RH, Finance, Fonction Publique, Management...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gereso.com\/actualites\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/c91814f92d627ed4715993fbbf7c7e8d\",\"name\":\"Damien P\u00e9an\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2016\/03\/damien-pean.jpg\",\"contentUrl\":\"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2016\/03\/damien-pean.jpg\",\"caption\":\"Damien P\u00e9an\"},\"description\":\"Damien P\u00c9AN est titulaire du Dipl\u00f4me d'\u00e9tudes sup\u00e9rieures comptables et financi\u00e8res (DESCF). Il intervient depuis plusieurs ann\u00e9es aupr\u00e8s d'\u00e9tudiants en licence de comptabilit\u00e9 et de gestion, \u00e0 qui il enseigne le contr\u00f4le de gestion, la comptabilit\u00e9 approfondie, le management, la fiscalit\u00e9, le droit des soci\u00e9t\u00e9s et le droit du travail. Il intervient \u00e9galement en formation continue pour le compte de divers organismes de formation sur des th\u00e9matiques techniques en comptabilit\u00e9 et fiscalit\u00e9. Il forme aussi un public de non-initi\u00e9s aux fondamentaux de la finance.\",\"url\":\"https:\/\/www.gereso.com\/actualites\/author\/d-pean\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Loi de finances pour 2022 : validation par le Conseil constitutionnel - Le Blog GERESO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/","og_locale":"fr_FR","og_type":"article","og_title":"Loi de finances pour 2022 : validation par le Conseil constitutionnel - Le Blog GERESO","og_description":"Le Conseil constitutionnel a valid\u00e9 ce mardi 28 d\u00e9cembre 2021 l\u2019essentiel des dispositions de la loi de finances pour 2022. Seuls 10 cavaliers l\u00e9gislatifs ont \u00e9t\u00e9 censur\u00e9s. Un budget consid\u00e9r\u00e9 comme sinc\u00e8re Adopt\u00e9e en lecture d\u00e9finitive le 15 d\u00e9cembre dernier par les d\u00e9put\u00e9s, la loi de finances pour 2022 a fait l\u2019objet de 3 recours [&hellip;]","og_url":"https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/","og_site_name":"Le Blog GERESO","article_published_time":"2021-12-29T10:56:43+00:00","article_modified_time":"2021-12-29T10:56:45+00:00","author":"Damien P\u00e9an","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/","url":"https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/","name":"Loi de finances pour 2022 : validation par le Conseil constitutionnel - Le Blog GERESO","isPartOf":{"@id":"https:\/\/www.gereso.com\/actualites\/#website"},"datePublished":"2021-12-29T10:56:43+00:00","dateModified":"2021-12-29T10:56:45+00:00","author":{"@id":"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/c91814f92d627ed4715993fbbf7c7e8d"},"breadcrumb":{"@id":"https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.gereso.com\/actualites\/2021\/12\/29\/loi-de-finances-pour-2022-validation-par-le-conseil-constitutionnel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gereso.com\/actualites\/"},{"@type":"ListItem","position":2,"name":"Loi de finances pour 2022 : validation par le Conseil constitutionnel"}]},{"@type":"WebSite","@id":"https:\/\/www.gereso.com\/actualites\/#website","url":"https:\/\/www.gereso.com\/actualites\/","name":"Le Blog GERESO","description":"Toute l&#039;actu RH, Finance, Fonction Publique, Management...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gereso.com\/actualites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/c91814f92d627ed4715993fbbf7c7e8d","name":"Damien P\u00e9an","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2016\/03\/damien-pean.jpg","contentUrl":"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2016\/03\/damien-pean.jpg","caption":"Damien P\u00e9an"},"description":"Damien P\u00c9AN est titulaire du Dipl\u00f4me d'\u00e9tudes sup\u00e9rieures comptables et financi\u00e8res (DESCF). Il intervient depuis plusieurs ann\u00e9es aupr\u00e8s d'\u00e9tudiants en licence de comptabilit\u00e9 et de gestion, \u00e0 qui il enseigne le contr\u00f4le de gestion, la comptabilit\u00e9 approfondie, le management, la fiscalit\u00e9, le droit des soci\u00e9t\u00e9s et le droit du travail. Il intervient \u00e9galement en formation continue pour le compte de divers organismes de formation sur des th\u00e9matiques techniques en comptabilit\u00e9 et fiscalit\u00e9. Il forme aussi un public de non-initi\u00e9s aux fondamentaux de la finance.","url":"https:\/\/www.gereso.com\/actualites\/author\/d-pean\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/posts\/24877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/comments?post=24877"}],"version-history":[{"count":1,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/posts\/24877\/revisions"}],"predecessor-version":[{"id":24878,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/posts\/24877\/revisions\/24878"}],"wp:attachment":[{"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/media?parent=24877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/categories?post=24877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/tags?post=24877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}