{"id":32461,"date":"2023-01-03T12:33:37","date_gmt":"2023-01-03T10:33:37","guid":{"rendered":"https:\/\/www.gereso.com\/actualites\/?p=32461"},"modified":"2023-01-03T12:33:39","modified_gmt":"2023-01-03T10:33:39","slug":"7-conseils-icare-rater-coup-sur-reunion-distance","status":"publish","type":"post","link":"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/","title":{"rendered":"7 conseils d&rsquo;ICARE pour rater \u00e0 coup s\u00fbr une r\u00e9union \u00e0 distance !"},"content":{"rendered":"\n<p>Selon l&rsquo;IFOP, un Cadre participait en moyenne \u00e0 3,5 r\u00e9unions par semaine en 2018. En 2021, son nombre moyen de r\u00e9unions hebdomadaires a bondi \u00e0 5,3. En synth\u00e8se nous organisons une fois et demie plus de r\u00e9unions qu&rsquo;il y a 3 ans. Le d\u00e9veloppement des Visioconf\u00e9rences, qui repr\u00e9sentent 56% des r\u00e9unions r\u00e9alis\u00e9es en 2021, expliquerait pour une grande part cette \u00e9volution : plus faciles \u00e0 organiser, moins sujettes aux discussions sans fin, r\u00e9pondant aux objectifs de d\u00e9carbonation et \u00e9tant tr\u00e8s adapt\u00e9es \u00e0 une organisation hybride du travail, cette fa\u00e7on de se r\u00e9unir s&rsquo;impose de plus en plus comme la r\u00e9f\u00e9rence du mode collaboratif.<\/p>\n\n\n\n<p>Alors pour \u00eatre certain(e) de rater l&rsquo;organisation et la conduite de ces r\u00e9unions \u00e0 distance&nbsp;:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li><strong>Invitez un maximum de monde<\/strong> : oui, pour quelles raisons devriez-vous vous priver ? Chacun de vos Coll\u00e8gues, m\u00eame s&rsquo;il n&rsquo;est pas indispensable au traitement du sujet, se trouve \u00e0 seulement un clic de votre r\u00e9union\u2026 et un public cons\u00e9quent compensera certainement son manque d&rsquo;interactivit\u00e9 !<\/li>\n\n\n\n<li><strong>Cibler le cr\u00e9neau du d\u00e9jeuner<\/strong>&nbsp;: si vous souhaitez que le maximum d&rsquo;invit\u00e9s soient disponibles, s\u00e9lectionnez des horaires de r\u00e9unions lors desquels vous \u00eates certains qu&rsquo;ils ne sont pas d\u00e9j\u00e0 en r\u00e9union, voire au travail&nbsp;; apr\u00e8s analyse le meilleur cr\u00e9neau semble \u00eatre celui du d\u00e9jeuner&nbsp;! &nbsp;<\/li>\n\n\n\n<li><strong>Limitez les \u00e9changes&nbsp;<\/strong>: discuter ou d\u00e9battre en Visioconf\u00e9rence est vraiment difficile, voire impossible tellement le brouhaha s&rsquo;installe rapidement&nbsp;; contentez-vous donc de pr\u00e9sentations \u00ab\u00a0descendantes\u00a0\u00bb et d&rsquo;expos\u00e9s persuasifs qui n&rsquo;appellent ni participation ni travail collaboratif\u2026 et pour \u00eatre tranquille, cadrez votre r\u00e9union en ce sens d\u00e8s son lancement&nbsp;!<\/li>\n\n\n\n<li><strong>Renoncez \u00e0 l&rsquo;Icebreaker<\/strong>&nbsp;: \u00e9tant donn\u00e9 que votre r\u00e9union sera un long monologue, il est absurde de vouloir accueillir et inclure vos participants&nbsp;; c&rsquo;est m\u00eame une perte de temps&nbsp;! Allez donc droit au but et faites passer votre message\u2026 plut\u00f4t que de tergiverser sur le fait que tout le monde se connaisse ou se sente \u00e0 l&rsquo;aise pour d\u00e9marrer la r\u00e9union.<\/li>\n\n\n\n<li><strong>Bannissez les supports technologiques&nbsp;<\/strong>: dans la m\u00eame logique d&rsquo;efficacit\u00e9, ne pr\u00e9voyez aucune solution digitale qui transformerait votre r\u00e9union en workshop&nbsp;; exit donc le chat, les syst\u00e8mes compliqu\u00e9s d&rsquo;annotation de documents, de post &lsquo;It d\u00e9mat\u00e9rialis\u00e9s ou de sondages \u00ab\u00a0QR cod\u00e9s\u00a0\u00bb, \u2026 ce ne sont que des gadgets pour geeks&nbsp;; quelques slides que vous d\u00e9roulerez \u00e0 l&rsquo;envi sont grandement suffisants pour animer une Visio agile et frugale&nbsp;!<\/li>\n\n\n\n<li><strong>Imposez l&rsquo;\u00e9cran noir&nbsp;<\/strong>: d&rsquo;ailleurs m\u00eame une cam\u00e9ra est superflue pour vos invit\u00e9s puisqu&rsquo;il n&rsquo;est pas question de les faire participer, encore moins de les surprendre dans leur intimit\u00e9 ou de les perturber dans leurs activit\u00e9s simultan\u00e9es&nbsp;!<\/li>\n\n\n\n<li><strong>Encouragez le multitasking&nbsp;<\/strong>: oui, pour augmenter leur efficacit\u00e9, incitez vos participants \u00e0 suivre votre r\u00e9union tout en assurant d&rsquo;autres t\u00e2ches pendant son d\u00e9roulement&nbsp;: traitement de leurs E-mail, r\u00e9daction du compte-rendu de la r\u00e9union pr\u00e9c\u00e9dente, planification de la r\u00e9union suivante\u2026 au niveau professionnel, mais aussi, s&rsquo;ils sont en t\u00e9l\u00e9travail, cuisine, repas, m\u00e9nage, \u2026 dans un registre plus personnel&nbsp;!<\/li>\n<\/ol>\n\n\n\n<p>Apr\u00e8s ces quelques cl\u00e9s pour rater \u00e0 coup s\u00fbr vos r\u00e9unions \u00e0 distance, notamment gr\u00e2ce \u00e0 des animations tr\u00e8s \u00ab\u00a0descendantes\u00a0\u00bb, ICARE vous donne rendez-vous le mois prochain pour vous proposer ses meilleures pratiques pour rater \u00e0 coup s\u00fbr une pr\u00e9sentation devant un public.<\/p>\n\n\n\n<p>Au plaisir de vous retrouver le mois prochain, nous vous souhaitons une excellente ann\u00e9e 2023 et esp\u00e9rons qu&rsquo;elle sera pleine de rat\u00e9s en tous genres.<\/p>\n\n\n\n<p><article class=\"obj_encart-formation\">\n<div class=\"ctn_encart\">\n<h3>Votre formation sur ce th\u00e8me<\/h3>\n<h2>&nbsp;CONDUIRE DES R\u00c9UNIONS PRODUCTIVES&nbsp;<\/h2>\n<h4>2 jours &#8211; En pr\u00e9sentiel ou \u00e0 distance<\/h4>\n<ul> \n<li><strong>D\u00e9finir l&rsquo;objectif de la r\u00e9union<\/strong> et construire un sc\u00e9nario d&rsquo;animation pertinent.<\/li>\n<li><strong>Pr\u00e9parer et faire pr\u00e9parer<\/strong>, par les futurs participants, une r\u00e9union de travail.<\/li>\n<li><strong>Introduire, piloter la r\u00e9union, cr\u00e9er une dynamique<\/strong> de groupe pour traiter efficacement les sujets.<\/li>\n<li><strong>R\u00e9agir en direct<\/strong> aux impr\u00e9vus et aux comportements \u00ab\u00a0d\u00e9viants\u00a0\u00bb des participants perturbateurs.<\/li>\n<li><strong>Rendre les participants<\/strong> \u00ab\u00a0auteurs\u00a0\u00bb et \u00ab\u00a0acteurs\u00a0\u00bb des d\u00e9cisions prises en r\u00e9union.<\/li>\n<\/ul>\n<div class=\"ctn_btn\">\n<a class=\"obj_btn\" target=\"_blank\" href=\"https:\/\/www.gereso.com\/REUN\" rel=\"noopener\"><span>En savoir plus<\/span><\/a>\n<a class=\"obj_btn\" target=\"_blank\" href=\"https:\/\/www.gereso.com\/client\/programme-pdf\/REUN.pdf\" rel=\"noopener\"><span>T\u00e9l\u00e9charger le programme PDF<\/span><\/a>\n<\/div>\n<\/div>\n<\/article><\/p>\n\n\n\n<table border=\"0\" bgcolor=\"#fafafa\" cellspacing=\"10\" cellpadding=\"10\" width=\"100%\"><tr>\n<td bgcolor=\"#fafafa\" style=\"border-left:15px solid #fafafa; border-right:15px solid #fafafa; border-top:15px solid #fafafa;\">\n<span style=\"color:#434546;font-size:20px;text-decoration:none;\"><center><b>L&rsquo;auteur<\/b><\/center><\/span>\n<p><strong><img decoding=\"async\" class=\"size-full wp-image-8994 alignleft\" src=\"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2021\/10\/Patrick-Van-Honacker.jpg\" alt=\"Patrick Van Honacker\" width=\"100\" height=\"130\"><\/strong>\n<b>Patrick Van Honacker<\/b><br>\nDe formation commerciale Patrick d\u00e9bute sa carri\u00e8re dans les forces de ventes du Groupe LACTALIS. Promu Manager tr\u00e8s jeune il suit de tr\u00e8s nombreuses formations, dont tout le catalogue manag\u00e9rial ICARE, pour apprendre et se perfectionner sans cesse dans le difficile exercice de l&rsquo;encadrement et l&rsquo;accompagnement des Hommes. Il croit \u00e0 un management qui concilie la recherche de la performance et du d\u00e9veloppement humain.<br>\nApr\u00e8s 15 ans dans la fonction commerciale dont 8 de Direction Nationale des Ventes il d\u00e9cide de prendre un virage professionnel humaniste et int\u00e8gre le P\u00f4le D\u00e9veloppement des Comp\u00e9tences du Groupe LACTALIS qu&rsquo;il dirige pendant 3 ans. <br>\nRiche d&rsquo;une double expertise en management et en Gestion des Ressources Humaines il rejoint en 2006 ICARE, son Organisme de Formation de c\u0153ur dont il a \u00e9prouv\u00e9 les m\u00e9thodes sur le terrain, pour accompagner les Hommes et leur Organisation dans la mise en \u0153uvre de relations authentiques, respectueuses, justes et d\u00e9veloppantes.<br>\nCoach, Consultant et Formateur certifi\u00e9 il dirige l&rsquo;Institut et conduit l&rsquo;\u00e9quipe p\u00e9dagogique ICARE depuis 2019. <\/p><\/td><\/tr><\/table>\n","protected":false},"excerpt":{"rendered":"<p>Selon l&rsquo;IFOP, un Cadre participait en moyenne \u00e0 3,5 r\u00e9unions par semaine en 2018. En 2021, son nombre moyen de r\u00e9unions hebdomadaires a bondi \u00e0 5,3. En synth\u00e8se nous organisons une fois et demie plus de r\u00e9unions qu&rsquo;il y a 3 ans. Le d\u00e9veloppement des Visioconf\u00e9rences, qui repr\u00e9sentent 56% des r\u00e9unions r\u00e9alis\u00e9es en 2021, expliquerait [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":32475,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_mi_skip_tracking":false,"footnotes":""},"categories":[12,10],"tags":[],"class_list":["post-32461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-management-et-leadership"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>7 conseils d&rsquo;ICARE pour rater \u00e0 coup s\u00fbr une r\u00e9union \u00e0 distance ! - Le Blog GERESO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 conseils d&rsquo;ICARE pour rater \u00e0 coup s\u00fbr une r\u00e9union \u00e0 distance ! - Le Blog GERESO\" \/>\n<meta property=\"og:description\" content=\"Selon l&rsquo;IFOP, un Cadre participait en moyenne \u00e0 3,5 r\u00e9unions par semaine en 2018. En 2021, son nombre moyen de r\u00e9unions hebdomadaires a bondi \u00e0 5,3. En synth\u00e8se nous organisons une fois et demie plus de r\u00e9unions qu&rsquo;il y a 3 ans. Le d\u00e9veloppement des Visioconf\u00e9rences, qui repr\u00e9sentent 56% des r\u00e9unions r\u00e9alis\u00e9es en 2021, expliquerait [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Blog GERESO\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-03T10:33:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-03T10:33:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2023\/01\/reunion-distance.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00c9quipe Icare\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/\",\"url\":\"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/\",\"name\":\"7 conseils d&rsquo;ICARE pour rater \u00e0 coup s\u00fbr une r\u00e9union \u00e0 distance ! - Le Blog GERESO\",\"isPartOf\":{\"@id\":\"https:\/\/www.gereso.com\/actualites\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2023\/01\/reunion-distance.jpg\",\"datePublished\":\"2023-01-03T10:33:37+00:00\",\"dateModified\":\"2023-01-03T10:33:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/6b2d9038abb3603efe7e320f8a180189\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/#primaryimage\",\"url\":\"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2023\/01\/reunion-distance.jpg\",\"contentUrl\":\"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2023\/01\/reunion-distance.jpg\",\"width\":600,\"height\":400,\"caption\":\"7 conseils d\u2019ICARE pour rater \u00e0 coup s\u00fbr une r\u00e9union \u00e0 distance !\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.gereso.com\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7 conseils d&rsquo;ICARE pour rater \u00e0 coup s\u00fbr une r\u00e9union \u00e0 distance !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/#website\",\"url\":\"https:\/\/www.gereso.com\/actualites\/\",\"name\":\"Le Blog GERESO\",\"description\":\"Toute l&#039;actu RH, Finance, Fonction Publique, Management...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gereso.com\/actualites\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/6b2d9038abb3603efe7e320f8a180189\",\"name\":\"\u00c9quipe Icare\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2021\/08\/Logo-Icare-120x120.jpg\",\"contentUrl\":\"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2021\/08\/Logo-Icare-120x120.jpg\",\"caption\":\"\u00c9quipe Icare\"},\"description\":\"Icare est un Institut dont les activit\u00e9s de formation, d'accompagnement et de conseil sont centr\u00e9es sur les th\u00e8mes de la communication, de la prise de parole en public, de la gestion des relations, du management et de la transmission des comp\u00e9tences. Ses prestations s\u2019adressent \u00e0 tous les collaborateurs et tous les managers souhaitant am\u00e9liorer de fa\u00e7on concr\u00e8te leurs postures, leurs comportements et leurs pratiques du quotidien. Son expertise s'appuie sur des intervenants tous coaches certifi\u00e9s et sur des m\u00e9thodes p\u00e9dagogiques tr\u00e8s participatives bas\u00e9es notamment sur le principe d'induction (partir de la r\u00e9alit\u00e9 des participants pour les accompagner vers les bonnes pratiques) et de tr\u00e8s nombreux tests, r\u00e9flexions, exercices et mises en situation. Anim\u00e9e depuis pr\u00e8s de 30 ans par une logique d'am\u00e9lioration continue l'organisation adh\u00e8re \u00e0 la F\u00e9d\u00e9ration de la Formation Professionnelle, est inscrite au Datadock et est certifi\u00e9e Qualiopi dans la cat\u00e9gorie des actions de formation.\",\"url\":\"https:\/\/www.gereso.com\/actualites\/author\/icare\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7 conseils d&rsquo;ICARE pour rater \u00e0 coup s\u00fbr une r\u00e9union \u00e0 distance ! - Le Blog GERESO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/","og_locale":"fr_FR","og_type":"article","og_title":"7 conseils d&rsquo;ICARE pour rater \u00e0 coup s\u00fbr une r\u00e9union \u00e0 distance ! - Le Blog GERESO","og_description":"Selon l&rsquo;IFOP, un Cadre participait en moyenne \u00e0 3,5 r\u00e9unions par semaine en 2018. En 2021, son nombre moyen de r\u00e9unions hebdomadaires a bondi \u00e0 5,3. En synth\u00e8se nous organisons une fois et demie plus de r\u00e9unions qu&rsquo;il y a 3 ans. Le d\u00e9veloppement des Visioconf\u00e9rences, qui repr\u00e9sentent 56% des r\u00e9unions r\u00e9alis\u00e9es en 2021, expliquerait [&hellip;]","og_url":"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/","og_site_name":"Le Blog GERESO","article_published_time":"2023-01-03T10:33:37+00:00","article_modified_time":"2023-01-03T10:33:39+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2023\/01\/reunion-distance.jpg","type":"image\/jpeg"}],"author":"\u00c9quipe Icare","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/","url":"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/","name":"7 conseils d&rsquo;ICARE pour rater \u00e0 coup s\u00fbr une r\u00e9union \u00e0 distance ! - Le Blog GERESO","isPartOf":{"@id":"https:\/\/www.gereso.com\/actualites\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/#primaryimage"},"image":{"@id":"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2023\/01\/reunion-distance.jpg","datePublished":"2023-01-03T10:33:37+00:00","dateModified":"2023-01-03T10:33:39+00:00","author":{"@id":"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/6b2d9038abb3603efe7e320f8a180189"},"breadcrumb":{"@id":"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/#primaryimage","url":"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2023\/01\/reunion-distance.jpg","contentUrl":"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2023\/01\/reunion-distance.jpg","width":600,"height":400,"caption":"7 conseils d\u2019ICARE pour rater \u00e0 coup s\u00fbr une r\u00e9union \u00e0 distance !"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gereso.com\/actualites\/2023\/01\/03\/7-conseils-icare-rater-coup-sur-reunion-distance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gereso.com\/actualites\/"},{"@type":"ListItem","position":2,"name":"7 conseils d&rsquo;ICARE pour rater \u00e0 coup s\u00fbr une r\u00e9union \u00e0 distance !"}]},{"@type":"WebSite","@id":"https:\/\/www.gereso.com\/actualites\/#website","url":"https:\/\/www.gereso.com\/actualites\/","name":"Le Blog GERESO","description":"Toute l&#039;actu RH, Finance, Fonction Publique, Management...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gereso.com\/actualites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/6b2d9038abb3603efe7e320f8a180189","name":"\u00c9quipe Icare","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.gereso.com\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2021\/08\/Logo-Icare-120x120.jpg","contentUrl":"https:\/\/www.gereso.com\/actualites\/wp-content\/uploads\/2021\/08\/Logo-Icare-120x120.jpg","caption":"\u00c9quipe Icare"},"description":"Icare est un Institut dont les activit\u00e9s de formation, d'accompagnement et de conseil sont centr\u00e9es sur les th\u00e8mes de la communication, de la prise de parole en public, de la gestion des relations, du management et de la transmission des comp\u00e9tences. Ses prestations s\u2019adressent \u00e0 tous les collaborateurs et tous les managers souhaitant am\u00e9liorer de fa\u00e7on concr\u00e8te leurs postures, leurs comportements et leurs pratiques du quotidien. Son expertise s'appuie sur des intervenants tous coaches certifi\u00e9s et sur des m\u00e9thodes p\u00e9dagogiques tr\u00e8s participatives bas\u00e9es notamment sur le principe d'induction (partir de la r\u00e9alit\u00e9 des participants pour les accompagner vers les bonnes pratiques) et de tr\u00e8s nombreux tests, r\u00e9flexions, exercices et mises en situation. Anim\u00e9e depuis pr\u00e8s de 30 ans par une logique d'am\u00e9lioration continue l'organisation adh\u00e8re \u00e0 la F\u00e9d\u00e9ration de la Formation Professionnelle, est inscrite au Datadock et est certifi\u00e9e Qualiopi dans la cat\u00e9gorie des actions de formation.","url":"https:\/\/www.gereso.com\/actualites\/author\/icare\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/posts\/32461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/comments?post=32461"}],"version-history":[{"count":17,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/posts\/32461\/revisions"}],"predecessor-version":[{"id":33857,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/posts\/32461\/revisions\/33857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/media\/32475"}],"wp:attachment":[{"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/media?parent=32461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/categories?post=32461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gereso.com\/actualites\/wp-json\/wp\/v2\/tags?post=32461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}